{"id":145,"count":275,"description":"","link":"https:\/\/www.alpineairtechnologies.com\/blog\/tag\/silent-thunder\/","name":"Silent Thunder","slug":"silent-thunder","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.alpineairtechnologies.com\/blog\/wp-json\/wp\/v2\/tags\/145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alpineairtechnologies.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.alpineairtechnologies.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.alpineairtechnologies.com\/blog\/wp-json\/wp\/v2\/posts?tags=145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}