{"id":243,"count":191,"description":"","link":"https:\/\/www.alpineairtechnologies.com\/blog\/tag\/breath-fresh-air\/","name":"Breath fresh air","slug":"breath-fresh-air","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.alpineairtechnologies.com\/blog\/wp-json\/wp\/v2\/tags\/243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alpineairtechnologies.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.alpineairtechnologies.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.alpineairtechnologies.com\/blog\/wp-json\/wp\/v2\/posts?tags=243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}